{"id":4304,"date":"2024-02-01T16:04:47","date_gmt":"2024-02-01T15:04:47","guid":{"rendered":"https:\/\/www.lideedeco.com\/?page_id=4304"},"modified":"2025-07-26T17:24:50","modified_gmt":"2025-07-26T15:24:50","slug":"agencement-et-decoration-dune-salle-deau-projet-loisin","status":"publish","type":"page","link":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/","title":{"rendered":"Agencement et d\u00e9coration d&rsquo;une salle d&rsquo;eau &#8211; Projet Loisin"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4304\" class=\"elementor elementor-4304\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-729272e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"729272e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c655c7e\" data-id=\"2c655c7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fc985d elementor-widget elementor-widget-text-editor\" data-id=\"8fc985d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\">Le projet :<\/span><\/p><p>Corinne et Philippe m&rsquo;ont demand\u00e9 de les accompagner dans leur projet de <strong>d\u00e9coration<\/strong> et d&rsquo;<strong>agencement<\/strong> de leur <strong>salle d&rsquo;ea<\/strong>u de <strong>4,10<\/strong> m\u00e8tres carr\u00e9s, pour leur suite parentale.\u00a0<\/p><p>A l&rsquo;origine de leur construction, les <strong>arriv\u00e9es et \u00e9vacuations<\/strong> <strong>d&rsquo;eaux<\/strong> avaient \u00e9t\u00e9 pr\u00e9vues. Entre temps l&rsquo;espace avait \u00e9t\u00e9 <strong>cloisonn\u00e9<\/strong> pour d\u00e9limiter deux armoires.\u00a0<\/p><p>L&rsquo;id\u00e9e principale \u00e0 donc \u00e9t\u00e9 de <strong>retirer ces cloisons<\/strong> pour un meilleur agencement, de <strong>red\u00e9limiter l&rsquo;espace<\/strong> avec un<strong> claustra<\/strong> et d&rsquo;int\u00e9grer des <strong>coffrages<\/strong> pour les conduits d&rsquo;\u00e9vacuations tout en se raccordant dessus.<\/p><p>Pour la d\u00e9coration leur souhait a \u00e9t\u00e9 que je leur cr\u00e9\u00e9e une ambiance inspir\u00e9e du <strong>style campagne<\/strong> avec une dominance de <strong>bois<\/strong> et l&rsquo;utilisation de <strong>carreaux de ciment<\/strong> dans des <strong>teintes douces.\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66be923 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66be923\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2594e67\" data-id=\"2594e67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e1bcc1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4e1bcc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tape\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc08cd6 elementor-widget elementor-widget-text-editor\" data-id=\"dc08cd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4,10 m2<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9696480\" data-id=\"9696480\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a3bb8a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1a3bb8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fbae70 elementor-widget elementor-widget-text-editor\" data-id=\"0fbae70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fa2059d\" data-id=\"fa2059d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f5658f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8f5658f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53754c4 elementor-widget elementor-widget-text-editor\" data-id=\"53754c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Loisin<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b287c7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b287c7b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e1f8f0\" data-id=\"7e1f8f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50ed5f0 elementor-widget elementor-widget-spacer\" data-id=\"50ed5f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f32a490 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f32a490\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b74483a\" data-id=\"b74483a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29dfdb5 elementor-widget elementor-widget-image\" data-id=\"29dfdb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"971\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_121636-1-e1740594546255-768x971.webp\" class=\"attachment-medium_large size-medium_large wp-image-4599 not-transparent\" alt=\"\" srcset=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_121636-1-e1740594546255-768x971.webp 768w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_121636-1-e1740594546255-237x300.webp 237w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_121636-1-e1740594546255-810x1024.webp 810w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_121636-1-e1740594546255.webp 878w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-has-transparency=\"false\" data-dominant-color=\"8d7e6c\" style=\"--dominant-color: #8d7e6c\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2aa7b5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2aa7b5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f32135c\" data-id=\"f32135c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b78959 elementor-widget elementor-widget-image\" data-id=\"5b78959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"1600\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0006.webp\" class=\"attachment-2048x2048 size-2048x2048 wp-image-4596 not-transparent\" alt=\"\" srcset=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0006.webp 900w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0006-169x300.webp 169w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0006-576x1024.webp 576w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0006-768x1365.webp 768w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0006-864x1536.webp 864w\" sizes=\"(max-width: 900px) 100vw, 900px\" data-has-transparency=\"false\" data-dominant-color=\"80786c\" style=\"--dominant-color: #80786c\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-29f1c53\" data-id=\"29f1c53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad66f05 elementor-widget elementor-widget-image\" data-id=\"ad66f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_130603-576x1024.webp\" class=\"attachment-large size-large wp-image-4594 not-transparent\" alt=\"Salle d&apos;eau de la suite par&apos;entale\" srcset=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_130603-576x1024.webp 576w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_130603-169x300.webp 169w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_130603-768x1365.webp 768w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG_20250122_130603.webp 823w\" sizes=\"(max-width: 576px) 100vw, 576px\" data-has-transparency=\"false\" data-dominant-color=\"857e70\" style=\"--dominant-color: #857e70\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d180c24\" data-id=\"d180c24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c73c079 elementor-widget elementor-widget-image\" data-id=\"c73c079\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0007-576x1024.webp\" class=\"attachment-large size-large wp-image-4597 not-transparent\" alt=\"\" srcset=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0007-576x1024.webp 576w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0007-169x300.webp 169w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0007-768x1365.webp 768w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0007-864x1536.webp 864w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2025\/02\/IMG-20240803-WA0007.webp 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" data-has-transparency=\"false\" data-dominant-color=\"7f7561\" style=\"--dominant-color: #7f7561\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6be1202 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6be1202\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e591d13\" data-id=\"e591d13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e27876d elementor-widget elementor-widget-spacer\" data-id=\"e27876d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21d2eed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21d2eed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14e9dea\" data-id=\"14e9dea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2322f02 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2322f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd68219 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd68219\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f93910\" data-id=\"4f93910\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b706ddc elementor-widget elementor-widget-text-editor\" data-id=\"b706ddc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Planche d&rsquo;ambiance, coupe et vues 3D<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb78a16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb78a16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92ee80b\" data-id=\"92ee80b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af6ed50 elementor-widget elementor-widget-spacer\" data-id=\"af6ed50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb1407 elementor-arrows-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"5bb1407\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive3-1.webp\" alt=\"diapositive3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive4.webp\" alt=\"diapositive4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive5.webp\" alt=\"diapositive5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive7.webp\" alt=\"diapositive7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive6-1.webp\" alt=\"diapositive6\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3e62da elementor-widget elementor-widget-image\" data-id=\"f3e62da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2023\/05\/IMG20230109154003.webp\" class=\"attachment-large size-large wp-image-3409\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd6ea2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dd6ea2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33ca6ad\" data-id=\"33ca6ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8198eef elementor-widget elementor-widget-spacer\" data-id=\"8198eef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11e86b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11e86b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89105c4\" data-id=\"89105c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df9db88 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"df9db88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30c6675 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30c6675\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdeed32\" data-id=\"cdeed32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8f93a4 elementor-widget elementor-widget-spacer\" data-id=\"d8f93a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d109c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d109c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b0cc56\" data-id=\"6b0cc56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3511ead elementor-widget elementor-widget-text-editor\" data-id=\"3511ead\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vues avant travaux<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9baa82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9baa82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5bf2449\" data-id=\"5bf2449\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d514006 elementor-widget elementor-widget-image\" data-id=\"d514006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img202311241644202-1536x2048.webp\" class=\"attachment-2048x2048 size-2048x2048 wp-image-4308 not-transparent\" alt=\"\" srcset=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img202311241644202-1536x2048.webp 1536w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img202311241644202-225x300.webp 225w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img202311241644202-768x1024.webp 768w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img202311241644202-1152x1536.webp 1152w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img202311241644202.webp 1834w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" data-has-transparency=\"false\" data-dominant-color=\"8f7c6b\" style=\"--dominant-color: #8f7c6b\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b7f7447\" data-id=\"b7f7447\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fb7d7d elementor-widget elementor-widget-image\" data-id=\"8fb7d7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164428-768x1024.webp\" class=\"attachment-large size-large wp-image-4307 not-transparent\" alt=\"\" srcset=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164428-768x1024.webp 768w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164428-225x300.webp 225w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164428-1152x1536.webp 1152w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164428-1536x2048.webp 1536w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164428.webp 1834w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-has-transparency=\"false\" data-dominant-color=\"8e7660\" style=\"--dominant-color: #8e7660\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5986bac\" data-id=\"5986bac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7077434 elementor-widget elementor-widget-image\" data-id=\"7077434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164443-1024x768.webp\" class=\"attachment-large size-large wp-image-4306 not-transparent\" alt=\"\" srcset=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164443-1024x768.webp 1024w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164443-300x225.webp 300w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164443-768x576.webp 768w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164443-1536x1152.webp 1536w, https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/img20231124164443-2048x1536.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-has-transparency=\"false\" data-dominant-color=\"968372\" style=\"--dominant-color: #968372\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd8724f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd8724f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15a3994\" data-id=\"15a3994\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c7f517 elementor-widget elementor-widget-spacer\" data-id=\"4c7f517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dade80 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9dade80\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-14093d6\" data-id=\"14093d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f8b479 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9f8b479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dun-appartement-de-colocataires-projet-amiens\/?preview_id=4648&#038;preview_nonce=e864f26a0b&#038;preview=true\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-step-backward\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-50259d1\" data-id=\"50259d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06a0079 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"06a0079\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-home\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1ee176c\" data-id=\"1ee176c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-057e354 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"057e354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dun-institut-de-beaute-projet-mia-cara\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-step-forward\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le projet : Corinne et Philippe m&rsquo;ont demand\u00e9 de les accompagner dans leur projet de d\u00e9coration et d&rsquo;agencement de leur salle d&rsquo;eau de 4,10 m\u00e8tres carr\u00e9s, pour leur suite parentale.\u00a0 A l&rsquo;origine de leur construction, les arriv\u00e9es et \u00e9vacuations d&rsquo;eaux avaient \u00e9t\u00e9 pr\u00e9vues. Entre temps l&rsquo;espace avait \u00e9t\u00e9 cloisonn\u00e9 pour d\u00e9limiter deux armoires.\u00a0 L&rsquo;id\u00e9e principale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4336,"parent":1044,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-4304","page","type-page","status-publish","has-post-thumbnail","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agencement et d\u00e9coration d&#039;une salle d&#039;eau - Projet Loisin - L&#039;id\u00e9e D\u00e9co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agencement et d\u00e9coration d&#039;une salle d&#039;eau - Projet Loisin - L&#039;id\u00e9e D\u00e9co\" \/>\n<meta property=\"og:description\" content=\"Le projet : Corinne et Philippe m&rsquo;ont demand\u00e9 de les accompagner dans leur projet de d\u00e9coration et d&rsquo;agencement de leur salle d&rsquo;eau de 4,10 m\u00e8tres carr\u00e9s, pour leur suite parentale.\u00a0 A l&rsquo;origine de leur construction, les arriv\u00e9es et \u00e9vacuations d&rsquo;eaux avaient \u00e9t\u00e9 pr\u00e9vues. Entre temps l&rsquo;espace avait \u00e9t\u00e9 cloisonn\u00e9 pour d\u00e9limiter deux armoires.\u00a0 L&rsquo;id\u00e9e principale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;id\u00e9e D\u00e9co\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-26T15:24:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive7-1-e1706891062221.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"557\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/\",\"url\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/\",\"name\":\"Agencement et d\u00e9coration d'une salle d'eau - Projet Loisin - L&#039;id\u00e9e D\u00e9co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lideedeco.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/diapositive7-1-e1706891062221.webp\",\"datePublished\":\"2024-02-01T15:04:47+00:00\",\"dateModified\":\"2025-07-26T15:24:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lideedeco.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/diapositive7-1-e1706891062221.webp\",\"contentUrl\":\"https:\\\/\\\/www.lideedeco.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/diapositive7-1-e1706891062221.webp\",\"width\":876,\"height\":557},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/agencement-et-decoration-dune-salle-deau-projet-loisin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lideedeco.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos r\u00e9alisations\",\"item\":\"https:\\\/\\\/www.lideedeco.com\\\/index.php\\\/nos-realisations-lideedeco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agencement et d\u00e9coration d&rsquo;une salle d&rsquo;eau &#8211; Projet Loisin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lideedeco.com\\\/\",\"name\":\"L&#039;id\u00e9e D\u00e9co\",\"description\":\"D\u00e9coration et agencement d&#039;espaces\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lideedeco.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/#organization\",\"name\":\"L&#039;id\u00e9e D\u00e9co\",\"url\":\"https:\\\/\\\/www.lideedeco.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lideedeco.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-png.png\",\"contentUrl\":\"https:\\\/\\\/www.lideedeco.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-png.png\",\"width\":1190,\"height\":1184,\"caption\":\"L&#039;id\u00e9e D\u00e9co\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lideedeco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/l.idee.deco\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agencement et d\u00e9coration d'une salle d'eau - Projet Loisin - L&#039;id\u00e9e D\u00e9co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/","og_locale":"fr_FR","og_type":"article","og_title":"Agencement et d\u00e9coration d'une salle d'eau - Projet Loisin - L&#039;id\u00e9e D\u00e9co","og_description":"Le projet : Corinne et Philippe m&rsquo;ont demand\u00e9 de les accompagner dans leur projet de d\u00e9coration et d&rsquo;agencement de leur salle d&rsquo;eau de 4,10 m\u00e8tres carr\u00e9s, pour leur suite parentale.\u00a0 A l&rsquo;origine de leur construction, les arriv\u00e9es et \u00e9vacuations d&rsquo;eaux avaient \u00e9t\u00e9 pr\u00e9vues. Entre temps l&rsquo;espace avait \u00e9t\u00e9 cloisonn\u00e9 pour d\u00e9limiter deux armoires.\u00a0 L&rsquo;id\u00e9e principale [&hellip;]","og_url":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/","og_site_name":"L&#039;id\u00e9e D\u00e9co","article_modified_time":"2025-07-26T15:24:50+00:00","og_image":[{"width":876,"height":557,"url":"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive7-1-e1706891062221.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/","url":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/","name":"Agencement et d\u00e9coration d'une salle d'eau - Projet Loisin - L&#039;id\u00e9e D\u00e9co","isPartOf":{"@id":"https:\/\/www.lideedeco.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/#primaryimage"},"image":{"@id":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive7-1-e1706891062221.webp","datePublished":"2024-02-01T15:04:47+00:00","dateModified":"2025-07-26T15:24:50+00:00","breadcrumb":{"@id":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/#primaryimage","url":"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive7-1-e1706891062221.webp","contentUrl":"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2024\/02\/diapositive7-1-e1706891062221.webp","width":876,"height":557},{"@type":"BreadcrumbList","@id":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/agencement-et-decoration-dune-salle-deau-projet-loisin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lideedeco.com\/"},{"@type":"ListItem","position":2,"name":"Nos r\u00e9alisations","item":"https:\/\/www.lideedeco.com\/index.php\/nos-realisations-lideedeco\/"},{"@type":"ListItem","position":3,"name":"Agencement et d\u00e9coration d&rsquo;une salle d&rsquo;eau &#8211; Projet Loisin"}]},{"@type":"WebSite","@id":"https:\/\/www.lideedeco.com\/#website","url":"https:\/\/www.lideedeco.com\/","name":"L&#039;id\u00e9e D\u00e9co","description":"D\u00e9coration et agencement d&#039;espaces","publisher":{"@id":"https:\/\/www.lideedeco.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lideedeco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lideedeco.com\/#organization","name":"L&#039;id\u00e9e D\u00e9co","url":"https:\/\/www.lideedeco.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lideedeco.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2023\/10\/cropped-logo-png.png","contentUrl":"https:\/\/www.lideedeco.com\/wp-content\/uploads\/2023\/10\/cropped-logo-png.png","width":1190,"height":1184,"caption":"L&#039;id\u00e9e D\u00e9co"},"image":{"@id":"https:\/\/www.lideedeco.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/l.idee.deco"]}]}},"_links":{"self":[{"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/pages\/4304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/comments?post=4304"}],"version-history":[{"count":23,"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/pages\/4304\/revisions"}],"predecessor-version":[{"id":4679,"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/pages\/4304\/revisions\/4679"}],"up":[{"embeddable":true,"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/pages\/1044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/media\/4336"}],"wp:attachment":[{"href":"https:\/\/www.lideedeco.com\/index.php\/wp-json\/wp\/v2\/media?parent=4304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}